{"id":37214,"date":"2022-01-10T19:58:47","date_gmt":"2022-01-10T19:58:47","guid":{"rendered":"https:\/\/navegantesoceanicos.com\/generalidades-atmosfera\/"},"modified":"2024-12-27T06:50:52","modified_gmt":"2024-12-27T06:50:52","slug":"generalidades-atmosfera","status":"publish","type":"post","link":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/","title":{"rendered":"Informa\u00e7\u00f5es gerais sobre a atmosfera"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;3px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; inline_fonts=&#8221;Amaranth,Abhaya Libre,ABeeZee&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 align=\"justify\"><span style=\"font-size: x-large;\"><strong><span style=\"color: #0900b5; font-family: Amaranth;\">Informa\u00e7\u00f5es gerais sobre a atmosfera\u200b.<\/span><\/strong><\/span><\/h2>\n<p><span style=\"color: #000000;\">A meteorologia determinar\u00e1 uma grande parte das decis\u00f5es do navegador e, em muitos casos, a meteorologia pode ser decisiva para o rumo do barco. Conhecer os aspectos mais te\u00f3ricos, como as generalidades sobre a atmosfera ou a sua circula\u00e7\u00e3o geral, permitir-nos-\u00e1 mais tarde conhecer em profundidade a natureza dos diferentes fen\u00f3menos meteorol\u00f3gicos que todo o bom skipper ou capit\u00e3o de barco deve dominar.<\/span><\/p>\n<p><span style=\"color: #000000;\">Neste primeiro cap\u00edtulo do livro online \u201cMETEOROLOGIA E OCEANOGRAFIA PARA NAVEGANTES OCE\u00c2NICOS\u201d, veremos os elementos que comp\u00f5em o ar da atmosfera e as diferentes camadas da atmosfera (troposfera, estratosfera, mesosfera, etc.) com as suas principais carater\u00edsticas.<div class=\"ihc-locker-wrap\"><div  class='ihc_locker_3'><div  class='lk_wrapper'><\/div><div class='lock_content'><h2>Este contenido solo est\u00e1 disponible para subscriptores de navegantesoceanicos.com<\/h2>\n<p>Efec\u00fae <strong>Log In<\/strong> para desbloquear.<\/p>\n<\/div><div class='lock_buttons'>\n  <!-- Login Form - Start -->\n  <div class=\"ihc-login-form-wrap ihc-login-template-9\">\n      <form method=\"post\" id=\"ihc_login_form\">\n          <input type=\"hidden\" name=\"ihcaction\" value=\"login\" \/>\n          <input type=\"hidden\" name=\"ihc_login_nonce\" value=\"e8fd24be50\" \/>\n\n          \n                    <!-- Username field -->\n          <div class=\"impu-form-line-fr\">\n              <i class=\"fa-ihc fa-username-ihc\"><\/i>\n              <input type=\"text\" value=\"\" name=\"log\" id=\"iump_login_username\" placeholder=\"Username\"\/>\n          <\/div>\n          <!-- End of username field -->\n          \n                    <!-- Password field -->\n          <div class=\"impu-form-line-fr\">\n              <i class=\"fa-ihc fa-pass-ihc\"><\/i>\n              <input type=\"password\" value=\"\" name=\"pwd\" id=\"iump_login_password\" placeholder=\"Password\"\/>\n              <span  class=\"ihc-hide-login-pw hide-if-no-js\" data-toggle=\"0\" aria-label=\"Show password\">\n              <span class=\"dashicons dashicons-visibility\" aria-hidden=\"true\"><\/span>\n                <\/span>\n          <\/div>\n          <!-- End of Password field -->\n          \n          \n          <!-- Remember me checkbox -->\n                    <div class=\"impu-remember-wrapper\">\n              <input type=\"checkbox\" value=\"forever\" name=\"rememberme\" class=\"impu-form-input-remember\" \/>\n              <span class=\"impu-form-label-fr impu-form-label-remember\">Manter sess\u00e3o<\/span>\n          <\/div>\n                    <!-- End of remember me --->\n\n                        <div class=\"impu-form-links-pass\"><a href=\"https:\/\/navegantesoceanicos.com\/iump-reset-password\/\">Lost your password?<\/a><\/div>\n          \n          <div class=\"ihc-clear\"><\/div>\n\n          <!-- captcha -->\n                    <!-- end of captcha -->\n\n          <!-- Submit bttn -->\n                        <div class=\"impu-form-line-fr impu-form-submit\">\n                  <input type=\"submit\" value=\"Log In\" name=\"Submit\"  class=\"button button-primary button-large\"\/>\n              <\/div>\n                    <!-- End of Submit bttn -->\n\n          <!-- Social -->\n                    <!-- End of Social -->\n\n          <!-- Additional links -->\n                        <div class=\"impu-form-links\">\n                  <div class=\"impu-form-links-reg\">Don&#039;t have an account?                      <a href=\"https:\/\/navegantesoceanicos.com\/iump-register\/\">Sign Up<\/a>\n                  <\/div>\n              <\/div>\n                    <!-- End of Aditional links -->\n\n      <\/form>\n  <\/div>\n\n  \n  <span class='ihc-js-login-data'\tdata-user_field='#iump_login_username' data-password_field='#iump_login_password' data-error_message='Por favor completa todos los campos requeridos!' ><\/span>\n  <!-- End of Login Form -->\n\n<\/div><\/div><\/div><\/span><\/strong><\/span><\/span><\/h2>\n<p align=\"justify\">[\/et_pb_text][et_pb_image src=&#8221;https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/08\/proteccion-web-con-ISSN.jpg&#8221; title_text=&#8221;protecci\u00f3n web con ISSN&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Primeiro cap\u00edtulo do livro online \u201cMeteorologia e Oceanografia para Navegantes Oce\u00e2nicos\u201d. Descri\u00e7\u00e3o da composi\u00e7\u00e3o e das camadas da atmosfera (Troposfera, Estratosfera, Mesosfera, Termosfera e Exosfera). Conceitos gerais de interesse para a compreens\u00e3o da meteorologia e oceanografia mar\u00edtimas.<\/p>\n","protected":false},"author":2,"featured_media":37215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_wp_rev_ctl_limit":""},"categories":[219,152],"tags":[],"class_list":["post-37214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meteorologia-e-oceanografia-para-navegantes-oceanicos","category-sem-categoria","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informa\u00e7\u00f5es gerais sobre a atmosfera - Navegantes Oce\u00e1nicos<\/title>\n<meta name=\"description\" content=\"Informa\u00e7\u00f5es gerais sobre a atmosfera. Livro online \u201cMeteorologia e Oceanografia para Navegantes Oce\u00e2nicos&quot;. Composi\u00e7\u00e3o e camadas da atmosfera.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informa\u00e7\u00f5es gerais sobre a atmosfera - Navegantes Oce\u00e1nicos\" \/>\n<meta property=\"og:description\" content=\"Informa\u00e7\u00f5es gerais sobre a atmosfera. Livro online \u201cMeteorologia e Oceanografia para Navegantes Oce\u00e2nicos&quot;. Composi\u00e7\u00e3o e camadas da atmosfera.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/\" \/>\n<meta property=\"og:site_name\" content=\"Navegantes Oce\u00e1nicos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Navegantes-Oce%c3%a1nicos-112578593494698\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-10T19:58:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-27T06:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Gonz\u00e1lez-Aller Lacalle\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Gonz\u00e1lez-Aller Lacalle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/\"},\"author\":{\"name\":\"Juan Gonz\u00e1lez-Aller Lacalle\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/4efe3afaef12467194c46aa710898a5c\"},\"headline\":\"Informa\u00e7\u00f5es gerais sobre a atmosfera\",\"datePublished\":\"2022-01-10T19:58:47+00:00\",\"dateModified\":\"2024-12-27T06:50:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/\"},\"wordCount\":1065,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/navegantesoceanicos.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg\",\"articleSection\":[\"Meteorologia e Oceanografia para Navegantes Oce\u00e2nicos\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/\",\"url\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/\",\"name\":\"Informa\u00e7\u00f5es gerais sobre a atmosfera - Navegantes Oce\u00e1nicos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/navegantesoceanicos.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg\",\"datePublished\":\"2022-01-10T19:58:47+00:00\",\"dateModified\":\"2024-12-27T06:50:52+00:00\",\"description\":\"Informa\u00e7\u00f5es gerais sobre a atmosfera. Livro online \u201cMeteorologia e Oceanografia para Navegantes Oce\u00e2nicos\\\". Composi\u00e7\u00e3o e camadas da atmosfera.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/navegantesoceanicos.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/navegantesoceanicos.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg\",\"width\":2560,\"height\":1810,\"caption\":\"CAPAS-DE-LA-ATMOSFERA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/generalidades-atmosfera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informa\u00e7\u00f5es gerais sobre a atmosfera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/\",\"name\":\"Navegantes Oce\u00e1nicos\",\"description\":\"Navegantes oce\u00e1nicos, te ayudamos a navegar, para navegantes, tripulantes, regatistas y armadores, escuela n\u00e1utica, libros on-line sobre t\u00e1cticas y equipamiento para la navegaci\u00f3n a vela, fondear, atracar, el manejo de las velas, electricidad a bordo, navegaci\u00f3n con mal tiempo, rutas oce\u00e1nicas y mucho m\u00e1s\",\"publisher\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#organization\",\"name\":\"Navegantes Oce\u00e1nicos\",\"url\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/navegantesoceanicos.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/LOGO-NAVEGANTES-OCEANICOS.png\",\"contentUrl\":\"https:\\\/\\\/navegantesoceanicos.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/LOGO-NAVEGANTES-OCEANICOS.png\",\"width\":1010,\"height\":814,\"caption\":\"Navegantes Oce\u00e1nicos\"},\"image\":{\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Navegantes-Oce\u00e1nicos-112578593494698\",\"https:\\\/\\\/www.instagram.com\\\/navegantes_oceanicos\\\/?hl=es\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXgDL_6xqE7rpdwNXRmzF_Q\\\/featured\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/4efe3afaef12467194c46aa710898a5c\",\"name\":\"Juan Gonz\u00e1lez-Aller Lacalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8262155dfd99d33a131c0b6f7c6d5b289bcc5a78eb8915b59699287a091367be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8262155dfd99d33a131c0b6f7c6d5b289bcc5a78eb8915b59699287a091367be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8262155dfd99d33a131c0b6f7c6d5b289bcc5a78eb8915b59699287a091367be?s=96&d=mm&r=g\",\"caption\":\"Juan Gonz\u00e1lez-Aller Lacalle\"},\"sameAs\":[\"https:\\\/\\\/navegantesoceanicos.com\"],\"url\":\"https:\\\/\\\/navegantesoceanicos.com\\\/pt-pt\\\/author\\\/juan-director\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informa\u00e7\u00f5es gerais sobre a atmosfera - Navegantes Oce\u00e1nicos","description":"Informa\u00e7\u00f5es gerais sobre a atmosfera. Livro online \u201cMeteorologia e Oceanografia para Navegantes Oce\u00e2nicos\". Composi\u00e7\u00e3o e camadas da atmosfera.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/","og_locale":"pt_PT","og_type":"article","og_title":"Informa\u00e7\u00f5es gerais sobre a atmosfera - Navegantes Oce\u00e1nicos","og_description":"Informa\u00e7\u00f5es gerais sobre a atmosfera. Livro online \u201cMeteorologia e Oceanografia para Navegantes Oce\u00e2nicos\". Composi\u00e7\u00e3o e camadas da atmosfera.","og_url":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/","og_site_name":"Navegantes Oce\u00e1nicos","article_publisher":"https:\/\/www.facebook.com\/Navegantes-Oce%c3%a1nicos-112578593494698","article_published_time":"2022-01-10T19:58:47+00:00","article_modified_time":"2024-12-27T06:50:52+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg","type":"image\/jpeg"}],"author":"Juan Gonz\u00e1lez-Aller Lacalle","twitter_misc":{"Escrito por":"Juan Gonz\u00e1lez-Aller Lacalle","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/#article","isPartOf":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/"},"author":{"name":"Juan Gonz\u00e1lez-Aller Lacalle","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#\/schema\/person\/4efe3afaef12467194c46aa710898a5c"},"headline":"Informa\u00e7\u00f5es gerais sobre a atmosfera","datePublished":"2022-01-10T19:58:47+00:00","dateModified":"2024-12-27T06:50:52+00:00","mainEntityOfPage":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/"},"wordCount":1065,"commentCount":0,"publisher":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/#primaryimage"},"thumbnailUrl":"https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg","articleSection":["Meteorologia e Oceanografia para Navegantes Oce\u00e2nicos"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/","url":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/","name":"Informa\u00e7\u00f5es gerais sobre a atmosfera - Navegantes Oce\u00e1nicos","isPartOf":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/#primaryimage"},"image":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/#primaryimage"},"thumbnailUrl":"https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg","datePublished":"2022-01-10T19:58:47+00:00","dateModified":"2024-12-27T06:50:52+00:00","description":"Informa\u00e7\u00f5es gerais sobre a atmosfera. Livro online \u201cMeteorologia e Oceanografia para Navegantes Oce\u00e2nicos\". Composi\u00e7\u00e3o e camadas da atmosfera.","breadcrumb":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/#primaryimage","url":"https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg","contentUrl":"https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg","width":2560,"height":1810,"caption":"CAPAS-DE-LA-ATMOSFERA"},{"@type":"BreadcrumbList","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/generalidades-atmosfera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/navegantesoceanicos.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Informa\u00e7\u00f5es gerais sobre a atmosfera"}]},{"@type":"WebSite","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#website","url":"https:\/\/navegantesoceanicos.com\/pt-pt\/","name":"Navegantes Oce\u00e1nicos","description":"Navegantes oce\u00e1nicos, te ayudamos a navegar, para navegantes, tripulantes, regatistas y armadores, escuela n\u00e1utica, libros on-line sobre t\u00e1cticas y equipamiento para la navegaci\u00f3n a vela, fondear, atracar, el manejo de las velas, electricidad a bordo, navegaci\u00f3n con mal tiempo, rutas oce\u00e1nicas y mucho m\u00e1s","publisher":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/navegantesoceanicos.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#organization","name":"Navegantes Oce\u00e1nicos","url":"https:\/\/navegantesoceanicos.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2019\/12\/LOGO-NAVEGANTES-OCEANICOS.png","contentUrl":"https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2019\/12\/LOGO-NAVEGANTES-OCEANICOS.png","width":1010,"height":814,"caption":"Navegantes Oce\u00e1nicos"},"image":{"@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Navegantes-Oce\u00e1nicos-112578593494698","https:\/\/www.instagram.com\/navegantes_oceanicos\/?hl=es","https:\/\/www.youtube.com\/channel\/UCXgDL_6xqE7rpdwNXRmzF_Q\/featured"]},{"@type":"Person","@id":"https:\/\/navegantesoceanicos.com\/pt-pt\/#\/schema\/person\/4efe3afaef12467194c46aa710898a5c","name":"Juan Gonz\u00e1lez-Aller Lacalle","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/8262155dfd99d33a131c0b6f7c6d5b289bcc5a78eb8915b59699287a091367be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8262155dfd99d33a131c0b6f7c6d5b289bcc5a78eb8915b59699287a091367be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8262155dfd99d33a131c0b6f7c6d5b289bcc5a78eb8915b59699287a091367be?s=96&d=mm&r=g","caption":"Juan Gonz\u00e1lez-Aller Lacalle"},"sameAs":["https:\/\/navegantesoceanicos.com"],"url":"https:\/\/navegantesoceanicos.com\/pt-pt\/author\/juan-director\/"}]}},"rttpg_featured_image_url":{"full":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg",2560,1810,false],"landscape":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg",2560,1810,false],"portraits":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg",2560,1810,false],"thumbnail":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-150x150.jpg",150,150,true],"medium":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-300x212.jpg",300,212,true],"large":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-1024x724.jpg",1024,724,true],"1536x1536":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-1536x1086.jpg",1536,1086,true],"2048x2048":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-2048x1448.jpg",2048,1448,true],"smart-post-landscape":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg",806,570,false],"smart-post-portrait":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg",600,424,false],"et-builder-post-main-image":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-400x250.jpg",400,250,true],"et-builder-post-main-image-fullwidth":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-1080x675.jpg",1080,675,true],"et-builder-portfolio-image":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-400x284.jpg",400,284,true],"et-builder-portfolio-image-single":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-1080x763.jpg",1080,763,true],"et-builder-gallery-image-portrait":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-400x516.jpg",400,516,true],"extra-image-huge":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-1280x768.jpg",1280,768,true],"extra-image-single-post":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-1280x640.jpg",1280,640,true],"extra-image-medium":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-627x376.jpg",627,376,true],"extra-image-small":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-440x264.jpg",440,264,true],"extra-image-square-medium":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-440x440.jpg",440,440,true],"extra-image-square-small":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-150x150.jpg",150,150,true],"woocommerce_thumbnail":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-300x212.jpg",300,212,true],"woocommerce_single":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-600x424.jpg",600,424,true],"woocommerce_gallery_thumbnail":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-100x100.jpg",100,100,true],"dgwt-wcas-product-suggestion":["https:\/\/navegantesoceanicos.com\/wp-content\/uploads\/2021\/09\/CAPAS-DE-LA-ATMOSFERA-1-scaled.jpg",64,45,false]},"rttpg_author":{"display_name":"Juan Gonz\u00e1lez-Aller Lacalle","author_link":"https:\/\/navegantesoceanicos.com\/pt-pt\/author\/juan-director\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/navegantesoceanicos.com\/pt-pt\/category\/meteorologia-e-oceanografia-para-navegantes-oceanicos\/\" rel=\"category tag\">Meteorologia e Oceanografia para Navegantes Oce\u00e2nicos<\/a> <a href=\"https:\/\/navegantesoceanicos.com\/pt-pt\/category\/sem-categoria\/\" rel=\"category tag\">Sem categoria<\/a>","rttpg_excerpt":"Primeiro cap\u00edtulo do livro online \u201cMeteorologia e Oceanografia para Navegantes Oce\u00e2nicos\u201d. Descri\u00e7\u00e3o da composi\u00e7\u00e3o e das camadas da atmosfera (Troposfera, Estratosfera, Mesosfera, Termosfera e Exosfera). Conceitos gerais de interesse para a compreens\u00e3o da meteorologia e oceanografia mar\u00edtimas.","_links":{"self":[{"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/posts\/37214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=37214"}],"version-history":[{"count":0,"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/posts\/37214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/media\/37215"}],"wp:attachment":[{"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=37214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=37214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/navegantesoceanicos.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=37214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}